{"id":42990,"date":"2021-05-16T18:28:33","date_gmt":"2021-05-16T18:28:33","guid":{"rendered":"https:\/\/www.radiouno.org\/site\/?p=42990"},"modified":"2021-05-16T20:36:05","modified_gmt":"2021-05-16T20:36:05","slug":"intervienen-fiesta-de-quinceanos-durante-toque-de-queda","status":"publish","type":"post","link":"https:\/\/www.radiouno.org\/site\/noticias\/42990\/intervienen-fiesta-de-quinceanos-durante-toque-de-queda\/","title":{"rendered":"Intervienen fiesta de quincea\u00f1os durante toque de queda\u00a0"},"content":{"rendered":"<p><span data-contrast=\"auto\">Una fiesta de quincea\u00f1os termin\u00f3 con cerca de 15 personas intervenidas por la Polic\u00eda Nacional y serenazgo del distrito Gregorio Albarrac\u00edn, debido a que se desarrollaba durante el toque de queda e infring\u00eda las normas sanitarias.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La intervenci\u00f3n ocurri\u00f3 en la asociaci\u00f3n de vivienda Las Magnolias, manzana K lote 17.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Los asistentes, al notar la presencia de los agentes, huyeron raudos hasta las habitaciones y el techo de la casa para evadir el operativo. Sin embargo, los efectivos los atraparon y los trasladaron a la comisar\u00eda, donde les impusieron las multas respectivas.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una fiesta de quincea\u00f1os termin\u00f3 con cerca de 15 personas intervenidas por la Polic\u00eda Nacional y serenazgo del distrito Gregorio Albarrac\u00edn, debido a que se desarrollaba durante el toque de queda e infring\u00eda las normas sanitarias.\u00a0 La intervenci\u00f3n ocurri\u00f3 en la asociaci\u00f3n de vivienda Las Magnolias, manzana K lote 17.\u00a0 Los asistentes, al notar la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":42992,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,26],"tags":[],"class_list":["post-42990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","category-portada"],"_links":{"self":[{"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/posts\/42990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/comments?post=42990"}],"version-history":[{"count":1,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/posts\/42990\/revisions"}],"predecessor-version":[{"id":42993,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/posts\/42990\/revisions\/42993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/media\/42992"}],"wp:attachment":[{"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/media?parent=42990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/categories?post=42990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/tags?post=42990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}