{"id":1263,"date":"2021-01-24T03:12:43","date_gmt":"2021-01-24T03:12:43","guid":{"rendered":"https:\/\/www.radiouno.org\/site\/?p=1263"},"modified":"2021-01-24T03:12:43","modified_gmt":"2021-01-24T03:12:43","slug":"la-labor-de-un-congresista-no-es-calentar-el-trasero-en-una-curul","status":"publish","type":"post","link":"https:\/\/www.radiouno.org\/site\/noticias\/1263\/la-labor-de-un-congresista-no-es-calentar-el-trasero-en-una-curul\/","title":{"rendered":"\u00abLa labor de un congresista no es calentar el trasero en una curul\u00bb"},"content":{"rendered":"<p>El candidato al Congreso por el partido RUNA, comandante de la Marina de Guerra del Per\u00fa (R), Ivan Ferrer, asegur\u00f3 que de ser electo har\u00e1 cumplir al Estado la deuda que tiene con Tacna.<!--more--><\/p>\n<p>\u201cEl Estado tiene una deuda con Tacna\u201d, asever\u00f3 el candidato al Congreso, Ivan Ferrer, quien a trav\u00e9s de Radio Uno afirm\u00f3 que de ser electo har\u00e1 que la regi\u00f3n reciba lo que por derecho le corresponde.<\/p>\n<p>\u201cImpulsaremos todo lo que tenga que ver con Tacna, no solo la Zona Franca, impulsar cualquier tipo de obra, infraestructura h\u00eddrica para solucionar la falta de agua. No se trata de vender solo populismo\u201d, expres\u00f3 el comandante de la Marina de Guerra del Per\u00fa en situaci\u00f3n de retiro.<\/p>\n<p>Mencion\u00f3 que, puede existir cualquier tipo de norma, pero si la pol\u00edtica p\u00fablica no va acompa\u00f1ada de una gesti\u00f3n p\u00fablica \u201cno habr\u00e1 soluci\u00f3n\u201d por lo que no dud\u00f3 en expresar que un legislador no puede solo hacer trabajo de escritorio.<\/p>\n<p>\u201cLa labor de un congresista no solo es estar calentando el trasero en una curul sino ir a la regi\u00f3n no solo en la semana de representaci\u00f3n, tiene que ir en cada momento y su labor principal es la de fiscalizar\u201d, dijo.<\/p>\n<p>Siendo as\u00ed critic\u00f3 que el Gobierno Regional de Tacna devolviera dinero al Estado. Para el aspirante a legislador \u201ces falta de iniciativa, de proactividad\u201d.<\/p>\n<p>Ferrer es secretario nacional del Partido Patri\u00f3tico del Per\u00fa, pero en alianza con el partido Renacimiento Unido Nacional es que participa en las elecciones 2021 con el n\u00famero 1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El candidato al Congreso por el partido RUNA, comandante de la Marina de Guerra del Per\u00fa (R), Ivan Ferrer, asegur\u00f3 que de ser electo har\u00e1 cumplir al Estado la deuda que tiene con Tacna.<\/p>\n","protected":false},"author":2,"featured_media":1264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/posts\/1263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/comments?post=1263"}],"version-history":[{"count":1,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/posts\/1263\/revisions"}],"predecessor-version":[{"id":1265,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/posts\/1263\/revisions\/1265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/media\/1264"}],"wp:attachment":[{"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/media?parent=1263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/categories?post=1263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiouno.org\/site\/wp-json\/wp\/v2\/tags?post=1263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}